{"id":4430,"date":"2020-08-20T13:41:34","date_gmt":"2020-08-20T16:41:34","guid":{"rendered":"http:\/\/gprimavera.org.br\/?p=4430"},"modified":"2020-08-20T13:41:34","modified_gmt":"2020-08-20T16:41:34","slug":"meninas-grupo-primavera-participam-de-exposicao-internacional","status":"publish","type":"post","link":"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/","title":{"rendered":"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional"},"content":{"rendered":"<p>As meninas do Grupo Primavera participaram da exposi\u00e7\u00e3o de artes internacional \u201c\u201cPLAYING WITH ART \u201d Children and Young People&#8221;, com o tema Quarantine Art \u2013 \u201cArt is life and survives\u201d \u2013 10th Edition. \u00c9 um projeto da Associa\u00e7\u00e3o Internacional de Artistas da Artcom Expo.<\/p>\n<p>Esta Exposi\u00e7\u00e3o Virtual busca promover o estudo e a dissemina\u00e7\u00e3o de Crian\u00e7as e Jovens Artistas Pl\u00e1sticos, com alunos de escolas e oficinas de arte. As inscri\u00e7\u00f5es para os participantes s\u00e3o feitas pelas entidades respons\u00e1veis pelos jovens artistas.<\/p>\n<p>Participaram da exposi\u00e7\u00e3o 16 meninas atendidas no Grupo Primavera. As obras, desenvolvidas sob a supervis\u00e3o da artista Ana Bittar. Todas as meninas receberam certificado de participa\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 12%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-4430 gallery-columns-8 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/adriele\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/adriele-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/adriele-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/adriele-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/adriele_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/adriele_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/adriele_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/adriele_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/ana\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ana-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ana-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ana-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/ana_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ana_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ana_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ana_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/braiany\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/braiany-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/braiany-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/braiany-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/braiany_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/braiany_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/braiany_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/braiany_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/debora\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/debora-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/debora-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/debora-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/debora_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/debora_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/debora_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/debora_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/emanuelle\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuelle-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuelle-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuelle-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/emanuelle_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuelle_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuelle_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuelle_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/emanuely\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuely-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuely-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuely-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/emanuely_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuely_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuely_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/emanuely_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/isabelle\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/isabelle_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/isabelle2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle2-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle2-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/isabelle2_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle2_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle2_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/isabelle2_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/jessica\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/jessica-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/jessica-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/jessica-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/jessica_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/jessica_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/jessica_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/jessica_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/julia\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/julia-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/julia-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/julia-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/julia_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/julia_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/julia_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/julia_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/livia\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/livia-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/livia-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/livia-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/livia_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/livia_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/livia_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/livia_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/ludmila\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ludmila-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ludmila-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ludmila-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/ludmila_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ludmila_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ludmila_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/ludmila_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/menina-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/menina-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/menina-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/menina-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/menina_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/menina_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/menina_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/menina_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/nicoli\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/nicoli-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/nicoli-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/nicoli-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/nicoli_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/nicoli_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/nicoli_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/nicoli_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/thaila\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/thaila_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/walentina\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/walentina-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/walentina-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/walentina-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/walentina_obra\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/walentina_obra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/walentina_obra-150x150.jpg 150w, https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/walentina_obra-66x66.jpg 66w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>As meninas do Grupo Primavera participaram da exposi\u00e7\u00e3o de artes internacional \u201c\u201cPLAYING WITH ART \u201d Children and Young People&#8221;, com o tema Quarantine Art \u2013 \u201cArt is life and survives\u201d \u2013 10th Edition. \u00c9 um projeto da Associa\u00e7\u00e3o Internacional de Artistas da Artcom Expo. Esta Exposi\u00e7\u00e3o Virtual busca promover o estudo e a dissemina\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional - Grupo Primavera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional - Grupo Primavera\" \/>\n<meta property=\"og:description\" content=\"As meninas do Grupo Primavera participaram da exposi\u00e7\u00e3o de artes internacional \u201c\u201cPLAYING WITH ART \u201d Children and Young People&#8221;, com o tema Quarantine Art \u2013 \u201cArt is life and survives\u201d \u2013 10th Edition. \u00c9 um projeto da Associa\u00e7\u00e3o Internacional de Artistas da Artcom Expo. Esta Exposi\u00e7\u00e3o Virtual busca promover o estudo e a dissemina\u00e7\u00e3o de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Primavera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grupoprimavera\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-20T16:41:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila_obra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grupo_primavera\" \/>\n<meta name=\"twitter:site\" content=\"@grupo_primavera\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/\",\"url\":\"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/\",\"name\":\"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional - Grupo Primavera\",\"isPartOf\":{\"@id\":\"https:\/\/gprimavera.org.br\/#website\"},\"datePublished\":\"2020-08-20T16:41:34+00:00\",\"dateModified\":\"2020-08-20T16:41:34+00:00\",\"author\":{\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/57ce31d100ae583f7296c3a36842e3bb\"},\"breadcrumb\":{\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/gprimavera.org.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gprimavera.org.br\/#website\",\"url\":\"https:\/\/gprimavera.org.br\/\",\"name\":\"Grupo Primavera\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gprimavera.org.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/57ce31d100ae583f7296c3a36842e3bb\",\"name\":\"Sergio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ce53f27d9705ebd3eb5af401397573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ce53f27d9705ebd3eb5af401397573d?s=96&d=mm&r=g\",\"caption\":\"Sergio\"},\"url\":\"https:\/\/gprimavera.org.br\/index.php\/author\/sergio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional - Grupo Primavera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/","og_locale":"pt_BR","og_type":"article","og_title":"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional - Grupo Primavera","og_description":"As meninas do Grupo Primavera participaram da exposi\u00e7\u00e3o de artes internacional \u201c\u201cPLAYING WITH ART \u201d Children and Young People&#8221;, com o tema Quarantine Art \u2013 \u201cArt is life and survives\u201d \u2013 10th Edition. \u00c9 um projeto da Associa\u00e7\u00e3o Internacional de Artistas da Artcom Expo. Esta Exposi\u00e7\u00e3o Virtual busca promover o estudo e a dissemina\u00e7\u00e3o de [&hellip;]","og_url":"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/","og_site_name":"Grupo Primavera","article_publisher":"https:\/\/www.facebook.com\/grupoprimavera","article_published_time":"2020-08-20T16:41:34+00:00","og_image":[{"width":510,"height":720,"url":"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2020\/08\/thaila_obra.jpg","type":"image\/jpeg"}],"author":"Sergio","twitter_card":"summary_large_image","twitter_creator":"@grupo_primavera","twitter_site":"@grupo_primavera","twitter_misc":{"Escrito por":"Sergio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/","url":"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/","name":"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional - Grupo Primavera","isPartOf":{"@id":"https:\/\/gprimavera.org.br\/#website"},"datePublished":"2020-08-20T16:41:34+00:00","dateModified":"2020-08-20T16:41:34+00:00","author":{"@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/57ce31d100ae583f7296c3a36842e3bb"},"breadcrumb":{"@id":"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gprimavera.org.br\/index.php\/2020\/08\/meninas-grupo-primavera-participam-de-exposicao-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/gprimavera.org.br\/"},{"@type":"ListItem","position":2,"name":"Meninas do Grupo Primavera participam de exposi\u00e7\u00e3o internacional"}]},{"@type":"WebSite","@id":"https:\/\/gprimavera.org.br\/#website","url":"https:\/\/gprimavera.org.br\/","name":"Grupo Primavera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gprimavera.org.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/57ce31d100ae583f7296c3a36842e3bb","name":"Sergio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ce53f27d9705ebd3eb5af401397573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ce53f27d9705ebd3eb5af401397573d?s=96&d=mm&r=g","caption":"Sergio"},"url":"https:\/\/gprimavera.org.br\/index.php\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts\/4430"}],"collection":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=4430"}],"version-history":[{"count":0,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts\/4430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/media\/4460"}],"wp:attachment":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=4430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=4430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=4430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}