{"id":3622,"date":"2017-06-07T16:34:58","date_gmt":"2017-06-07T19:34:58","guid":{"rendered":"http:\/\/gprimavera.org.br\/?p=3622"},"modified":"2017-06-07T16:34:58","modified_gmt":"2017-06-07T19:34:58","slug":"roda-viva-primavera-com-mariana-conti","status":"publish","type":"post","link":"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/","title":{"rendered":"Roda Viva Primavera com Mariana Conti"},"content":{"rendered":"<p>Segunda, 05 de junho, nossas alunas da turma La\u00e7os IV tiveram a oportunidade de participar do Roda Viva Primavera, uma roda de conversa que fazemos todos anos com alguma participa\u00e7\u00e3o especial. Nesta edi\u00e7\u00e3o a vereadora Mariana Conti foi convidada para discutirmos o tema &#8220;Pol\u00edticas P\u00fablicas para a juventude&#8221;. Foi uma manh\u00e3 de grande aprendizado para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segunda, 05 de junho, nossas alunas da turma La\u00e7os IV tiveram a oportunidade de participar do Roda Viva Primavera, uma roda de conversa que fazemos todos anos com alguma participa\u00e7\u00e3o especial. Nesta edi\u00e7\u00e3o a vereadora Mariana Conti foi convidada para discutirmos o tema &#8220;Pol\u00edticas P\u00fablicas para a juventude&#8221;. Foi uma manh\u00e3 de grande aprendizado para [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roda Viva Primavera com Mariana Conti - Grupo Primavera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roda Viva Primavera com Mariana Conti - Grupo Primavera\" \/>\n<meta property=\"og:description\" content=\"Segunda, 05 de junho, nossas alunas da turma La\u00e7os IV tiveram a oportunidade de participar do Roda Viva Primavera, uma roda de conversa que fazemos todos anos com alguma participa\u00e7\u00e3o especial. Nesta edi\u00e7\u00e3o a vereadora Mariana Conti foi convidada para discutirmos o tema &#8220;Pol\u00edticas P\u00fablicas para a juventude&#8221;. Foi uma manh\u00e3 de grande aprendizado para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Primavera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grupoprimavera\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-07T19:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2017\/06\/roda-viva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elisandra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grupo_primavera\" \/>\n<meta name=\"twitter:site\" content=\"@grupo_primavera\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elisandra\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/\",\"url\":\"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/\",\"name\":\"Roda Viva Primavera com Mariana Conti - Grupo Primavera\",\"isPartOf\":{\"@id\":\"https:\/\/gprimavera.org.br\/#website\"},\"datePublished\":\"2017-06-07T19:34:58+00:00\",\"dateModified\":\"2017-06-07T19:34:58+00:00\",\"author\":{\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234\"},\"breadcrumb\":{\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/gprimavera.org.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roda Viva Primavera com Mariana Conti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gprimavera.org.br\/#website\",\"url\":\"https:\/\/gprimavera.org.br\/\",\"name\":\"Grupo Primavera\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gprimavera.org.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234\",\"name\":\"elisandra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g\",\"caption\":\"elisandra\"},\"url\":\"https:\/\/gprimavera.org.br\/index.php\/author\/elisandra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roda Viva Primavera com Mariana Conti - Grupo Primavera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/","og_locale":"pt_BR","og_type":"article","og_title":"Roda Viva Primavera com Mariana Conti - Grupo Primavera","og_description":"Segunda, 05 de junho, nossas alunas da turma La\u00e7os IV tiveram a oportunidade de participar do Roda Viva Primavera, uma roda de conversa que fazemos todos anos com alguma participa\u00e7\u00e3o especial. Nesta edi\u00e7\u00e3o a vereadora Mariana Conti foi convidada para discutirmos o tema &#8220;Pol\u00edticas P\u00fablicas para a juventude&#8221;. Foi uma manh\u00e3 de grande aprendizado para [&hellip;]","og_url":"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/","og_site_name":"Grupo Primavera","article_publisher":"https:\/\/www.facebook.com\/grupoprimavera","article_published_time":"2017-06-07T19:34:58+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2017\/06\/roda-viva.jpg","type":"image\/jpeg"}],"author":"elisandra","twitter_card":"summary_large_image","twitter_creator":"@grupo_primavera","twitter_site":"@grupo_primavera","twitter_misc":{"Escrito por":"elisandra"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/","url":"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/","name":"Roda Viva Primavera com Mariana Conti - Grupo Primavera","isPartOf":{"@id":"https:\/\/gprimavera.org.br\/#website"},"datePublished":"2017-06-07T19:34:58+00:00","dateModified":"2017-06-07T19:34:58+00:00","author":{"@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234"},"breadcrumb":{"@id":"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gprimavera.org.br\/index.php\/2017\/06\/roda-viva-primavera-com-mariana-conti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/gprimavera.org.br\/"},{"@type":"ListItem","position":2,"name":"Roda Viva Primavera com Mariana Conti"}]},{"@type":"WebSite","@id":"https:\/\/gprimavera.org.br\/#website","url":"https:\/\/gprimavera.org.br\/","name":"Grupo Primavera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gprimavera.org.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234","name":"elisandra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g","caption":"elisandra"},"url":"https:\/\/gprimavera.org.br\/index.php\/author\/elisandra\/"}]}},"_links":{"self":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3622"}],"collection":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=3622"}],"version-history":[{"count":0,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/media\/3625"}],"wp:attachment":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=3622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=3622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=3622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}