{"id":3472,"date":"2016-11-18T16:13:19","date_gmt":"2016-11-18T19:13:19","guid":{"rendered":"http:\/\/gprimavera.org.br\/?p=3472"},"modified":"2016-11-18T16:13:19","modified_gmt":"2016-11-18T19:13:19","slug":"primeiro-torneio-de-basquete-do-jardim-sao-marcos","status":"publish","type":"post","link":"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/","title":{"rendered":"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos"},"content":{"rendered":"<p><em>A a\u00e7\u00e3o ser\u00e1 neste s\u00e1bado (19\/11), a partir das 8h30, e \u00e9 uma realiza\u00e7\u00e3o do Projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>O projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno da institui\u00e7\u00e3o, realiza neste s\u00e1bado, a partir das 8h30, no Centro de Artes e Esportes Unificados (CEU), o Primeiro Torneio de Basquete de Rua do Jardim S\u00e3o Marcos, em Campinas.<\/p>\n<p>Os times, com pelo menos tr\u00eas participantes, s\u00e3o formados por crian\u00e7as e adolescentes entre 11 e 14 anos de idade, nas categorias masculino e feminino. A expectativa \u00e9 que pelo menos 40 moradores dessa regi\u00e3o inscrevam-se para disputar essa primeira edi\u00e7\u00e3o do campeonato.<\/p>\n<p>Os interessados podem fazer a inscri\u00e7\u00e3o no local e devem colaborar com a entrega de um quilo de alimento n\u00e3o perec\u00edvel para participar do torneio. As arrecada\u00e7\u00f5es ser\u00e3o posteriormente entregues a fam\u00edlias carentes da regi\u00e3o do Jardim S\u00e3o Marcos, Vila Esperan\u00e7a e Campineiro.<\/p>\n<p>Al\u00e9m da entrega de medalhas aos vencedores, a a\u00e7\u00e3o contar\u00e1 com apresenta\u00e7\u00f5es culturais, como teatro e dan\u00e7as.<\/p>\n<p>&nbsp;<\/p>\n<p><u>Servi\u00e7o<\/u>:<\/p>\n<p><strong>Torneio de basquete de rua<\/strong><\/p>\n<p>Data: 19\/11 (s\u00e1bado).<\/p>\n<p>Hor\u00e1rio: das 8h30 \u00e0s 14 horas.<\/p>\n<p>Local: CEU da Vila Esperan\u00e7a (Rua Andr\u00e9 Grab\u00f3is, sem n\u00famero, Vila Esperan\u00e7a, Campinas-SP).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A a\u00e7\u00e3o ser\u00e1 neste s\u00e1bado (19\/11), a partir das 8h30, e \u00e9 uma realiza\u00e7\u00e3o do Projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno \u00a0 O projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno da institui\u00e7\u00e3o, realiza neste s\u00e1bado, a partir das 8h30, no Centro de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos - Grupo Primavera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos - Grupo Primavera\" \/>\n<meta property=\"og:description\" content=\"A a\u00e7\u00e3o ser\u00e1 neste s\u00e1bado (19\/11), a partir das 8h30, e \u00e9 uma realiza\u00e7\u00e3o do Projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno \u00a0 O projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno da institui\u00e7\u00e3o, realiza neste s\u00e1bado, a partir das 8h30, no Centro de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Primavera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grupoprimavera\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-18T19:13:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2016\/11\/cartaz-torneio-de-basquete-1-e1479496371458.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"487\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elisandra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grupo_primavera\" \/>\n<meta name=\"twitter:site\" content=\"@grupo_primavera\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elisandra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/\",\"url\":\"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/\",\"name\":\"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos - Grupo Primavera\",\"isPartOf\":{\"@id\":\"https:\/\/gprimavera.org.br\/#website\"},\"datePublished\":\"2016-11-18T19:13:19+00:00\",\"dateModified\":\"2016-11-18T19:13:19+00:00\",\"author\":{\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234\"},\"breadcrumb\":{\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/gprimavera.org.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gprimavera.org.br\/#website\",\"url\":\"https:\/\/gprimavera.org.br\/\",\"name\":\"Grupo Primavera\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gprimavera.org.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234\",\"name\":\"elisandra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gprimavera.org.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g\",\"caption\":\"elisandra\"},\"url\":\"https:\/\/gprimavera.org.br\/index.php\/author\/elisandra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos - Grupo Primavera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/","og_locale":"pt_BR","og_type":"article","og_title":"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos - Grupo Primavera","og_description":"A a\u00e7\u00e3o ser\u00e1 neste s\u00e1bado (19\/11), a partir das 8h30, e \u00e9 uma realiza\u00e7\u00e3o do Projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno \u00a0 O projeto Construindo Pontes, idealizado pela ONG Grupo Primavera e outras entidades do entorno da institui\u00e7\u00e3o, realiza neste s\u00e1bado, a partir das 8h30, no Centro de [&hellip;]","og_url":"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/","og_site_name":"Grupo Primavera","article_publisher":"https:\/\/www.facebook.com\/grupoprimavera","article_published_time":"2016-11-18T19:13:19+00:00","og_image":[{"width":487,"height":377,"url":"https:\/\/gprimavera.org.br\/wp-content\/uploads\/2016\/11\/cartaz-torneio-de-basquete-1-e1479496371458.jpg","type":"image\/jpeg"}],"author":"elisandra","twitter_card":"summary_large_image","twitter_creator":"@grupo_primavera","twitter_site":"@grupo_primavera","twitter_misc":{"Escrito por":"elisandra","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/","url":"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/","name":"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos - Grupo Primavera","isPartOf":{"@id":"https:\/\/gprimavera.org.br\/#website"},"datePublished":"2016-11-18T19:13:19+00:00","dateModified":"2016-11-18T19:13:19+00:00","author":{"@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234"},"breadcrumb":{"@id":"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gprimavera.org.br\/index.php\/2016\/11\/primeiro-torneio-de-basquete-do-jardim-sao-marcos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/gprimavera.org.br\/"},{"@type":"ListItem","position":2,"name":"Primeiro Torneio de Basquete do Jardim S\u00e3o Marcos"}]},{"@type":"WebSite","@id":"https:\/\/gprimavera.org.br\/#website","url":"https:\/\/gprimavera.org.br\/","name":"Grupo Primavera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gprimavera.org.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/72dd91e1c6e2f73bd24d8402c6620234","name":"elisandra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gprimavera.org.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b63c9acb00bccf938c131241f518a1a?s=96&d=mm&r=g","caption":"elisandra"},"url":"https:\/\/gprimavera.org.br\/index.php\/author\/elisandra\/"}]}},"_links":{"self":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3472"}],"collection":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=3472"}],"version-history":[{"count":0,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/posts\/3472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/media\/3473"}],"wp:attachment":[{"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=3472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=3472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gprimavera.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=3472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}